{"id":2897,"date":"2022-10-04T14:16:45","date_gmt":"2022-10-04T14:16:45","guid":{"rendered":"https:\/\/vocecom.cdlcaxias.com.br\/wp-content\/uploads\/2022\/10\/NatalCDLCaxias2022_Creditos_AlencarTurella-233.jpg"},"modified":"2022-10-04T14:16:45","modified_gmt":"2022-10-04T14:16:45","slug":"natalcdlcaxias2022_creditos_alencarturella-233","status":"inherit","type":"attachment","link":"https:\/\/vocecom.cdlcaxias.com.br\/index.php\/pgc_simply_gallery\/natal-cdl-caxias-2021\/natalcdlcaxias2022_creditos_alencarturella-233\/","title":{"rendered":"NatalCDLCaxias2022_Creditos_AlencarTurella (233)"},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"pgc_sgb_lightbox_settings":""},"class_list":["post-2897","attachment","type-attachment","status-inherit","hentry"],"featured_media_urls":{"thumbnail":["https:\/\/vocecom.cdlcaxias.com.br\/wp-content\/uploads\/2022\/10\/NatalCDLCaxias2022_Creditos_AlencarTurella-233-150x150.jpg",150,150,true],"medium":["https:\/\/vocecom.cdlcaxias.com.br\/wp-content\/uploads\/2022\/10\/NatalCDLCaxias2022_Creditos_AlencarTurella-233-300x200.jpg",300,200,true],"medium_large":["https:\/\/vocecom.cdlcaxias.com.br\/wp-content\/uploads\/2022\/10\/NatalCDLCaxias2022_Creditos_AlencarTurella-233-768x512.jpg",768,512,true],"large":["https:\/\/vocecom.cdlcaxias.com.br\/wp-content\/uploads\/2022\/10\/NatalCDLCaxias2022_Creditos_AlencarTurella-233-1024x683.jpg",790,527,true],"1536x1536":["https:\/\/vocecom.cdlcaxias.com.br\/wp-content\/uploads\/2022\/10\/NatalCDLCaxias2022_Creditos_AlencarTurella-233-1536x1024.jpg",1536,1024,true],"2048x2048":["https:\/\/vocecom.cdlcaxias.com.br\/wp-content\/uploads\/2022\/10\/NatalCDLCaxias2022_Creditos_AlencarTurella-233.jpg",1920,1280,false],"portfolio_item-thumbnail":["https:\/\/vocecom.cdlcaxias.com.br\/wp-content\/uploads\/2022\/10\/NatalCDLCaxias2022_Creditos_AlencarTurella-233-600x400.jpg",600,400,true],"portfolio_item-masonry":["https:\/\/vocecom.cdlcaxias.com.br\/wp-content\/uploads\/2022\/10\/NatalCDLCaxias2022_Creditos_AlencarTurella-233-600x400.jpg",600,400,true],"portfolio_item-thumbnail_cinema":["https:\/\/vocecom.cdlcaxias.com.br\/wp-content\/uploads\/2022\/10\/NatalCDLCaxias2022_Creditos_AlencarTurella-233-800x335.jpg",800,335,true],"portfolio_item-thumbnail_portrait":["https:\/\/vocecom.cdlcaxias.com.br\/wp-content\/uploads\/2022\/10\/NatalCDLCaxias2022_Creditos_AlencarTurella-233-600x900.jpg",600,900,true],"portfolio_item-thumbnail_square":["https:\/\/vocecom.cdlcaxias.com.br\/wp-content\/uploads\/2022\/10\/NatalCDLCaxias2022_Creditos_AlencarTurella-233-800x800.jpg",800,800,true]},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/vocecom.cdlcaxias.com.br\/wp-content\/uploads\/2022\/10\/NatalCDLCaxias2022_Creditos_AlencarTurella-233.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/vocecom.cdlcaxias.com.br\/wp-content\/uploads\/2022\/10\/NatalCDLCaxias2022_Creditos_AlencarTurella-233-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/vocecom.cdlcaxias.com.br\/wp-content\/uploads\/2022\/10\/NatalCDLCaxias2022_Creditos_AlencarTurella-233-300x200.jpg 300w, https:\/\/vocecom.cdlcaxias.com.br\/wp-content\/uploads\/2022\/10\/NatalCDLCaxias2022_Creditos_AlencarTurella-233-1024x683.jpg 1024w, https:\/\/vocecom.cdlcaxias.com.br\/wp-content\/uploads\/2022\/10\/NatalCDLCaxias2022_Creditos_AlencarTurella-233-768x512.jpg 768w, https:\/\/vocecom.cdlcaxias.com.br\/wp-content\/uploads\/2022\/10\/NatalCDLCaxias2022_Creditos_AlencarTurella-233-1536x1024.jpg 1536w, https:\/\/vocecom.cdlcaxias.com.br\/wp-content\/uploads\/2022\/10\/NatalCDLCaxias2022_Creditos_AlencarTurella-233-600x400.jpg 600w, https:\/\/vocecom.cdlcaxias.com.br\/wp-content\/uploads\/2022\/10\/NatalCDLCaxias2022_Creditos_AlencarTurella-233.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1920,"height":1280,"file":"2022\/10\/NatalCDLCaxias2022_Creditos_AlencarTurella-233.jpg","filesize":335946,"sizes":{"medium":{"file":"NatalCDLCaxias2022_Creditos_AlencarTurella-233-300x200.jpg","width":300,"height":200,"filesize":17454,"mime_type":"image\/jpeg","source_url":"https:\/\/vocecom.cdlcaxias.com.br\/wp-content\/uploads\/2022\/10\/NatalCDLCaxias2022_Creditos_AlencarTurella-233-300x200.jpg"},"large":{"file":"NatalCDLCaxias2022_Creditos_AlencarTurella-233-1024x683.jpg","width":1024,"height":683,"filesize":143849,"mime_type":"image\/jpeg","source_url":"https:\/\/vocecom.cdlcaxias.com.br\/wp-content\/uploads\/2022\/10\/NatalCDLCaxias2022_Creditos_AlencarTurella-233-1024x683.jpg"},"thumbnail":{"file":"NatalCDLCaxias2022_Creditos_AlencarTurella-233-150x150.jpg","width":150,"height":150,"filesize":7341,"mime_type":"image\/jpeg","source_url":"https:\/\/vocecom.cdlcaxias.com.br\/wp-content\/uploads\/2022\/10\/NatalCDLCaxias2022_Creditos_AlencarTurella-233-150x150.jpg"},"medium_large":{"file":"NatalCDLCaxias2022_Creditos_AlencarTurella-233-768x512.jpg","width":768,"height":512,"filesize":86548,"mime_type":"image\/jpeg","source_url":"https:\/\/vocecom.cdlcaxias.com.br\/wp-content\/uploads\/2022\/10\/NatalCDLCaxias2022_Creditos_AlencarTurella-233-768x512.jpg"},"1536x1536":{"file":"NatalCDLCaxias2022_Creditos_AlencarTurella-233-1536x1024.jpg","width":1536,"height":1024,"filesize":282356,"mime_type":"image\/jpeg","source_url":"https:\/\/vocecom.cdlcaxias.com.br\/wp-content\/uploads\/2022\/10\/NatalCDLCaxias2022_Creditos_AlencarTurella-233-1536x1024.jpg"},"portfolio_item-thumbnail":{"file":"NatalCDLCaxias2022_Creditos_AlencarTurella-233-600x400.jpg","width":600,"height":400,"filesize":56451,"mime_type":"image\/jpeg","source_url":"https:\/\/vocecom.cdlcaxias.com.br\/wp-content\/uploads\/2022\/10\/NatalCDLCaxias2022_Creditos_AlencarTurella-233-600x400.jpg"},"portfolio_item-masonry":{"file":"NatalCDLCaxias2022_Creditos_AlencarTurella-233-600x400.jpg","width":600,"height":400,"filesize":56451,"mime_type":"image\/jpeg","source_url":"https:\/\/vocecom.cdlcaxias.com.br\/wp-content\/uploads\/2022\/10\/NatalCDLCaxias2022_Creditos_AlencarTurella-233-600x400.jpg"},"portfolio_item-thumbnail_cinema":{"file":"NatalCDLCaxias2022_Creditos_AlencarTurella-233-800x335.jpg","width":800,"height":335,"filesize":64580,"mime_type":"image\/jpeg","source_url":"https:\/\/vocecom.cdlcaxias.com.br\/wp-content\/uploads\/2022\/10\/NatalCDLCaxias2022_Creditos_AlencarTurella-233-800x335.jpg"},"portfolio_item-thumbnail_portrait":{"file":"NatalCDLCaxias2022_Creditos_AlencarTurella-233-600x900.jpg","width":600,"height":900,"filesize":104480,"mime_type":"image\/jpeg","source_url":"https:\/\/vocecom.cdlcaxias.com.br\/wp-content\/uploads\/2022\/10\/NatalCDLCaxias2022_Creditos_AlencarTurella-233-600x900.jpg"},"portfolio_item-thumbnail_square":{"file":"NatalCDLCaxias2022_Creditos_AlencarTurella-233-800x800.jpg","width":800,"height":800,"filesize":125646,"mime_type":"image\/jpeg","source_url":"https:\/\/vocecom.cdlcaxias.com.br\/wp-content\/uploads\/2022\/10\/NatalCDLCaxias2022_Creditos_AlencarTurella-233-800x800.jpg"},"full":{"file":"NatalCDLCaxias2022_Creditos_AlencarTurella-233.jpg","width":1920,"height":1280,"mime_type":"image\/jpeg","source_url":"https:\/\/vocecom.cdlcaxias.com.br\/wp-content\/uploads\/2022\/10\/NatalCDLCaxias2022_Creditos_AlencarTurella-233.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":75,"source_url":"https:\/\/vocecom.cdlcaxias.com.br\/wp-content\/uploads\/2022\/10\/NatalCDLCaxias2022_Creditos_AlencarTurella-233.jpg","_links":{"self":[{"href":"https:\/\/vocecom.cdlcaxias.com.br\/index.php\/wp-json\/wp\/v2\/media\/2897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vocecom.cdlcaxias.com.br\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/vocecom.cdlcaxias.com.br\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/vocecom.cdlcaxias.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/vocecom.cdlcaxias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2897"}],"wp:attached-to":[{"embeddable":true,"post_type":"pgc_simply_gallery","id":75,"href":"https:\/\/vocecom.cdlcaxias.com.br\/index.php\/wp-json\/wp\/v2\/pgc_simply_gallery\/75"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}